{"id":886,"date":"2018-10-19T15:07:53","date_gmt":"2018-10-19T08:07:53","guid":{"rendered":"https:\/\/fenr2016.org\/home\/?page_id=886"},"modified":"2018-10-30T14:13:39","modified_gmt":"2018-10-30T07:13:39","slug":"%e0%b8%aa%e0%b8%b7%e0%b9%88%e0%b8%ad","status":"publish","type":"page","link":"https:\/\/fenr2016.org\/home\/%e0%b8%aa%e0%b8%b7%e0%b9%88%e0%b8%ad\/","title":{"rendered":"\u0e2a\u0e37\u0e48\u0e2d"},"content":{"rendered":"<div id=\"pl-886\"  class=\"panel-layout\" ><div id=\"pg-886-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-886-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-886-0-0-0\" class=\"so-panel widget widget_sow-post-carousel panel-first-child panel-last-child\" data-index=\"0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-post-carousel so-widget-sow-post-carousel-base-ad93eedad001-886\"\n\t\t\t\n\t\t>\t<div\n\t\tclass=\"sow-post-carousel-wrapper sow-post-carousel-theme-base\"\n\t\tstyle=\"overflow: hidden; max-width: 100%; min-height: 182px\"\n\t>\n\t\t<div class=\"sow-carousel-title has-title\">\n\t<h3 class=\"widget-title\">\u0e23\u0e39\u0e1b\u0e20\u0e32\u0e1e<\/h3>\t\t<div class=\"sow-carousel-navigation \">\n\t\t\t\t\t\t<a href=\"#\" class=\"sow-carousel-next\" title=\"Next\" aria-label=\"Next Posts\" role=\"button\"><\/a>\n\t\t\t\t\t\t<a href=\"#\" class=\"sow-carousel-previous\" title=\"Previous\" aria-label=\"Previous Posts\" role=\"button\"><\/a>\n\t\t\t\t\t<\/div>\n\t<\/div>\n\n<div class=\"sow-carousel-container \">\n\t\t<div class=\"sow-carousel-wrapper\"\n\t\tdata-dir=\"ltr\"\n\t\tstyle=\"opacity: 0;\"\n\t\tdata-widget=\"post\" data-fetching=\"false\" data-page=\"1\" data-ajax-url=\"https:\/\/fenr2016.org\/home\/wp-admin\/admin-ajax.php?_widgets_nonce=408bf2dbf8\" data-item_count=\"2\" data-carousel_settings=\"{&quot;loop&quot;:true,&quot;animation&quot;:&quot;Ease&quot;,&quot;animation_speed&quot;:400,&quot;autoplay&quot;:&quot;&quot;,&quot;pauseOnHover&quot;:&quot;&quot;,&quot;autoplaySpeed&quot;:8000,&quot;item_overflow&quot;:true,&quot;autoplay_continuous_scroll&quot;:false}\" data-responsive=\"{&quot;desktop_slides_to_scroll&quot;:1,&quot;tablet_landscape_breakpoint&quot;:1366,&quot;tablet_landscape_slides_to_scroll&quot;:2,&quot;tablet_portrait_breakpoint&quot;:1025,&quot;tablet_portrait_slides_to_scroll&quot;:2,&quot;mobile_breakpoint&quot;:480,&quot;mobile_slides_to_scroll&quot;:1}\" data-variable_width=\"true\" \t>\n\t\t<div\n\t\t\tclass=\"sow-carousel-items\"\n\t\t\t\t\t>\n\t\t\t\t<div class=\"sow-carousel-item\" tabindex=\"-1\" style=\"float: left;\">\n\t\t<div class=\"sow-carousel-thumbnail\">\n\t\t\t\t\t\t\t<a\n\t\t\t\t\thref=\"https:\/\/fenr2016.org\/home\/%e0%b8%aa%e0%b8%b7%e0%b9%88%e0%b8%ad\/%e0%b8%a1%e0%b8%99%e0%b8%95%e0%b9%8c%e0%b9%80%e0%b8%aa%e0%b8%99%e0%b9%88%e0%b8%ab%e0%b9%8c%e0%b9%81%e0%b8%ab%e0%b9%88%e0%b8%87%e0%b8%97%e0%b8%a7%e0%b8%b2%e0%b8%a2\/\"\n\t\t\t\t\t\t\t\t\t\tstyle=\"background-image:inherit\"\n\t\t\t\t\taria-labelledby=\"sow-carousel-id-1190\"\n\t\t\t\t\ttabindex=\"-1\"\n\t\t\t\t data-bg-image=\"url( https:\/\/fenr2016.org\/home\/wp-content\/uploads\/2018\/12\/\u0e21\u0e19\u0e15\u0e4c\u0e40\u0e2a\u0e19\u0e48\u0e2b\u0e4c\u0e41\u0e2b\u0e48\u0e07\u0e17\u0e27\u0e32\u0e22-2-272x182.jpg )\" class=\"lazyload\">\n\t\t\t\t\t<span class=\"overlay\"><\/span>\n\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t<h3 class=\"sow-carousel-item-title\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/fenr2016.org\/home\/%e0%b8%aa%e0%b8%b7%e0%b9%88%e0%b8%ad\/%e0%b8%a1%e0%b8%99%e0%b8%95%e0%b9%8c%e0%b9%80%e0%b8%aa%e0%b8%99%e0%b9%88%e0%b8%ab%e0%b9%8c%e0%b9%81%e0%b8%ab%e0%b9%88%e0%b8%87%e0%b8%97%e0%b8%a7%e0%b8%b2%e0%b8%a2\/\"\n\t\t\t\tid=\"sow-carousel-id-1190\"\n\t\t\t\t\t\t\t\ttabindex=\"-1\"\n\t\t\t>\n\n\t\t\t\t\u0e21\u0e19\u0e15\u0e4c\u0e40\u0e2a\u0e19\u0e48\u0e2b\u0e4c\u0e41\u0e2b\u0e48\u0e07\u0e17\u0e27\u0e32\u0e22\t\t\t<\/a>\n\t\t<\/h3>\n\t<\/div>\n\t\t<div class=\"sow-carousel-item\" tabindex=\"-1\" style=\"float: left;\">\n\t\t<div class=\"sow-carousel-thumbnail\">\n\t\t\t\t\t\t\t<a\n\t\t\t\t\thref=\"https:\/\/fenr2016.org\/home\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%a1%e0%b8%a7%e0%b8%a5%e0%b8%a0%e0%b8%b2%e0%b8%9e\/%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%88%e0%b8%b2%e0%b8%81%e0%b9%82%e0%b8%84%e0%b8%a3%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3\/\"\n\t\t\t\t\t\t\t\t\t\tstyle=\"background-image:inherit\"\n\t\t\t\t\taria-labelledby=\"sow-carousel-id-563\"\n\t\t\t\t\ttabindex=\"-1\"\n\t\t\t\t data-bg-image=\"url( https:\/\/fenr2016.org\/home\/wp-content\/uploads\/2018\/06\/IMG_0794-272x182.jpg )\" class=\"lazyload\">\n\t\t\t\t\t<span class=\"overlay\"><\/span>\n\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t<h3 class=\"sow-carousel-item-title\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/fenr2016.org\/home\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%a1%e0%b8%a7%e0%b8%a5%e0%b8%a0%e0%b8%b2%e0%b8%9e\/%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%88%e0%b8%b2%e0%b8%81%e0%b9%82%e0%b8%84%e0%b8%a3%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3\/\"\n\t\t\t\tid=\"sow-carousel-id-563\"\n\t\t\t\t\t\t\t\ttabindex=\"-1\"\n\t\t\t>\n\n\t\t\t\t\u0e20\u0e32\u0e1e\u0e08\u0e32\u0e01\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\t\t\t<\/a>\n\t\t<\/h3>\n\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t<\/div>\n\t\t<input type=\"hidden\" name=\"instance_hash\" value=\"e0eabfe9\"\/>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div id=\"pg-886-1\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-886-1-0\"  class=\"panel-grid-cell\" ><div id=\"panel-886-1-0-0\" class=\"so-panel widget widget_sow-post-carousel panel-first-child panel-last-child\" data-index=\"1\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-post-carousel so-widget-sow-post-carousel-base-ad93eedad001-563\"\n\t\t\t\n\t\t>\t<div\n\t\tclass=\"sow-post-carousel-wrapper sow-post-carousel-theme-base\"\n\t\tstyle=\"overflow: hidden; max-width: 100%; min-height: 182px\"\n\t>\n\t\t<div class=\"sow-carousel-title has-title\">\n\t<h3 class=\"widget-title\">Graphic<\/h3>\t\t<div class=\"sow-carousel-navigation \">\n\t\t\t\t\t\t<a href=\"#\" class=\"sow-carousel-next\" title=\"Next\" aria-label=\"Next Posts\" role=\"button\"><\/a>\n\t\t\t\t\t\t<a href=\"#\" class=\"sow-carousel-previous\" title=\"Previous\" aria-label=\"Previous Posts\" role=\"button\"><\/a>\n\t\t\t\t\t<\/div>\n\t<\/div>\n\n<div class=\"sow-carousel-container \">\n\t\t<div class=\"sow-carousel-wrapper\"\n\t\tdata-dir=\"ltr\"\n\t\tstyle=\"opacity: 0;\"\n\t\tdata-widget=\"post\" data-fetching=\"false\" data-page=\"1\" data-ajax-url=\"https:\/\/fenr2016.org\/home\/wp-admin\/admin-ajax.php?_widgets_nonce=408bf2dbf8\" data-item_count=\"2\" data-carousel_settings=\"{&quot;loop&quot;:true,&quot;animation&quot;:&quot;Ease&quot;,&quot;animation_speed&quot;:400,&quot;autoplay&quot;:&quot;&quot;,&quot;pauseOnHover&quot;:&quot;&quot;,&quot;autoplaySpeed&quot;:8000,&quot;item_overflow&quot;:true,&quot;autoplay_continuous_scroll&quot;:false}\" data-responsive=\"{&quot;desktop_slides_to_scroll&quot;:1,&quot;tablet_landscape_breakpoint&quot;:1366,&quot;tablet_landscape_slides_to_scroll&quot;:2,&quot;tablet_portrait_breakpoint&quot;:1025,&quot;tablet_portrait_slides_to_scroll&quot;:2,&quot;mobile_breakpoint&quot;:480,&quot;mobile_slides_to_scroll&quot;:1}\" data-variable_width=\"true\" \t>\n\t\t<div\n\t\t\tclass=\"sow-carousel-items\"\n\t\t\t\t\t>\n\t\t\t\t<div class=\"sow-carousel-item\" tabindex=\"-1\" style=\"float: left;\">\n\t\t<div class=\"sow-carousel-thumbnail\">\n\t\t\t\t\t\t\t<a\n\t\t\t\t\thref=\"https:\/\/fenr2016.org\/home\/%e0%b8%81%e0%b8%a3%e0%b8%b2%e0%b8%9f%e0%b8%9f%e0%b8%b4%e0%b8%84\/%e0%b8%97%e0%b8%b3%e0%b8%ad%e0%b8%a2%e0%b9%88%e0%b8%b2%e0%b8%87%e0%b9%84%e0%b8%a3-%e0%b9%80%e0%b8%a1%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%81%e0%b8%8e%e0%b8%ab%e0%b8%a1%e0%b8%b2%e0%b8%a2%e0%b9%84%e0%b8%a1\/\"\n\t\t\t\t\t\t\t\t\t\tstyle=\"background-image:inherit\"\n\t\t\t\t\taria-labelledby=\"sow-carousel-id-1162\"\n\t\t\t\t\ttabindex=\"-1\"\n\t\t\t\t data-bg-image=\"url( https:\/\/fenr2016.org\/home\/wp-content\/uploads\/2018\/11\/Legal-Analysis-I-272x182.jpg )\" class=\"lazyload\">\n\t\t\t\t\t<span class=\"overlay\"><\/span>\n\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t<h3 class=\"sow-carousel-item-title\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/fenr2016.org\/home\/%e0%b8%81%e0%b8%a3%e0%b8%b2%e0%b8%9f%e0%b8%9f%e0%b8%b4%e0%b8%84\/%e0%b8%97%e0%b8%b3%e0%b8%ad%e0%b8%a2%e0%b9%88%e0%b8%b2%e0%b8%87%e0%b9%84%e0%b8%a3-%e0%b9%80%e0%b8%a1%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%81%e0%b8%8e%e0%b8%ab%e0%b8%a1%e0%b8%b2%e0%b8%a2%e0%b9%84%e0%b8%a1\/\"\n\t\t\t\tid=\"sow-carousel-id-1162\"\n\t\t\t\t\t\t\t\ttabindex=\"-1\"\n\t\t\t>\n\n\t\t\t\t\u0e17\u0e33\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23? \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e44\u0e21\u0e48\u0e02\u0e49\u0e32\u0e21\u0e1e\u0e23\u0e21\u0e41\u0e14\u0e19\t\t\t<\/a>\n\t\t<\/h3>\n\t<\/div>\n\t\t<div class=\"sow-carousel-item\" tabindex=\"-1\" style=\"float: left;\">\n\t\t<div class=\"sow-carousel-thumbnail\">\n\t\t\t\t\t\t\t<a\n\t\t\t\t\thref=\"https:\/\/fenr2016.org\/home\/%e0%b8%81%e0%b8%a3%e0%b8%b2%e0%b8%9f%e0%b8%9f%e0%b8%b4%e0%b8%84\/%e0%b9%80%e0%b8%a1%e0%b8%b7%e0%b9%88%e0%b8%ad-eia-%e0%b9%84%e0%b8%a1%e0%b9%88%e0%b8%82%e0%b9%89%e0%b8%b2%e0%b8%a1%e0%b8%9e%e0%b8%a3%e0%b8%a1%e0%b9%81%e0%b8%94%e0%b8%99\/\"\n\t\t\t\t\t\t\t\t\t\tstyle=\"background-image:inherit\"\n\t\t\t\t\taria-labelledby=\"sow-carousel-id-1000\"\n\t\t\t\t\ttabindex=\"-1\"\n\t\t\t\t data-bg-image=\"url( https:\/\/fenr2016.org\/home\/wp-content\/uploads\/2018\/10\/181019-NR-Thai7-272x182.jpg )\" class=\"lazyload\">\n\t\t\t\t\t<span class=\"overlay\"><\/span>\n\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t<h3 class=\"sow-carousel-item-title\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/fenr2016.org\/home\/%e0%b8%81%e0%b8%a3%e0%b8%b2%e0%b8%9f%e0%b8%9f%e0%b8%b4%e0%b8%84\/%e0%b9%80%e0%b8%a1%e0%b8%b7%e0%b9%88%e0%b8%ad-eia-%e0%b9%84%e0%b8%a1%e0%b9%88%e0%b8%82%e0%b9%89%e0%b8%b2%e0%b8%a1%e0%b8%9e%e0%b8%a3%e0%b8%a1%e0%b9%81%e0%b8%94%e0%b8%99\/\"\n\t\t\t\tid=\"sow-carousel-id-1000\"\n\t\t\t\t\t\t\t\ttabindex=\"-1\"\n\t\t\t>\n\n\t\t\t\t\u0e40\u0e21\u0e37\u0e48\u0e2d EIA \u0e44\u0e21\u0e48\u0e02\u0e49\u0e32\u0e21\u0e1e\u0e23\u0e21\u0e41\u0e14\u0e19\t\t\t<\/a>\n\t\t<\/h3>\n\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t<\/div>\n\t\t<input type=\"hidden\" name=\"instance_hash\" value=\"560b8812\"\/>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>\u0e23\u0e39\u0e1b\u0e20\u0e32\u0e1e \u0e21\u0e19\u0e15\u0e4c\u0e40\u0e2a\u0e19\u0e48\u0e2b\u0e4c\u0e41\u0e2b\u0e48\u0e07\u0e17\u0e27\u0e32\u0e22 \u0e20\u0e32\u0e1e\u0e08\u0e32\u0e01\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 Graphic \u0e17\u0e33\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23?&hellip; <a class=\"read-more-link\" href=\"https:\/\/fenr2016.org\/home\/%e0%b8%aa%e0%b8%b7%e0%b9%88%e0%b8%ad\/\">Read More<\/a><\/p>\n","protected":false},"author":1,"featured_media":548,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-886","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/fenr2016.org\/home\/wp-json\/wp\/v2\/pages\/886","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fenr2016.org\/home\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/fenr2016.org\/home\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/fenr2016.org\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fenr2016.org\/home\/wp-json\/wp\/v2\/comments?post=886"}],"version-history":[{"count":13,"href":"https:\/\/fenr2016.org\/home\/wp-json\/wp\/v2\/pages\/886\/revisions"}],"predecessor-version":[{"id":1140,"href":"https:\/\/fenr2016.org\/home\/wp-json\/wp\/v2\/pages\/886\/revisions\/1140"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fenr2016.org\/home\/wp-json\/wp\/v2\/media\/548"}],"wp:attachment":[{"href":"https:\/\/fenr2016.org\/home\/wp-json\/wp\/v2\/media?parent=886"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}